{"id":110357,"date":"2021-01-13T16:49:26","date_gmt":"2021-01-14T00:49:26","guid":{"rendered":"https:\/\/www.mercadokeys.com\/product\/rogue-legacy-2-pc-steam-key-global\/"},"modified":"2022-06-29T06:09:50","modified_gmt":"2022-06-29T13:09:50","slug":"rogue-legacy-2-pc-steam-key-global","status":"publish","type":"product","link":"https:\/\/www.mercadokeys.com.mx\/eng\/product\/rogue-legacy-2-pc-steam-key-global\/","title":{"rendered":"Rogue Legacy 2 Steam CD Key"},"content":{"rendered":"<p><span style=\"vertical-align: inherit\">Rogue Legacy 2 es un p\u00edcaro LITE geneal\u00f3gico. Eso significa que tiene todas las trampas de un p\u00edcaro t\u00edpico (carreras aleatorias, personajes cambiantes y m\u00e1s), pero con actualizaciones persistentes y herederos muertos persistentes. En este juego, tu legado te define. Gasta el de tus padres<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Rogue Legacy 2 es un p\u00edcaro LITE geneal\u00f3gico. Eso significa que tiene todas las trampas de un p\u00edcaro t\u00edpico (carreras aleatorias, personajes cambiantes y m\u00e1s), pero con actualizaciones persistentes y herederos muertos persistentes. En este juego, tu legado te define. Gasta el de tus padres<\/p>","protected":false},"featured_media":111067,"template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"product_brand":[],"product_cat":[1501,2981,1271,1283,1280,1273,1392,1394,1393,1298,1425,1427,1423],"product_tag":[2801,2800,2799,1526],"class_list":{"0":"post-110357","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-tienda-de-videojuegos-ultimos-juegos-tijuana-mexico","7":"product_cat-destacados","8":"product_cat-tienda-de-videojuegos-tijuana-mexico","9":"product_cat-tienda-de-videojuegos-plataformas-tijuana-mexico","10":"product_cat-tienda-de-videojuegos-pc-tijuana-mexico","11":"product_cat-tienda-de-videojuegos-steam-key-tijuana-mexico","12":"product_cat-tienda-de-videojuegos-accion-tijuana-mexico","13":"product_cat-tienda-de-videojuegos-aventura-tijuana-mexico","14":"product_cat-tienda-de-videojuegos-indie-tijuana-mexico","15":"product_cat-tienda-de-videojuegos-rol-tijuana-mexico","16":"product_cat-tienda-de-videojuegos-acceso-anticipado-tijuana-mexico","17":"product_cat-tienda-de-videojuegos-juegos-para-mando-tijuana-mexico","18":"product_cat-tienda-de-videojuegos-nuevos-lanzamientos-tijuana-mexico","19":"product_tag-rogue-legacy","20":"product_tag-rogue-legacy-2","21":"product_tag-rogue-legacy-2-steam","22":"product_tag-steam","24":"first","25":"instock","26":"shipping-taxable","27":"purchasable","28":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rogue Legacy 2 Steam CD Key - MERCADOKEYS<\/title>\n<meta name=\"description\" content=\"El juego Rogue Legacy 2 es un p\u00edcaro LITE geneal\u00f3gico. Eso significa que tiene todas las trampas de un p\u00edcaro t\u00edpico dentro del mismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mercadokeys.com\/product\/rogue-legacy-2-pc-steam-key-global\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rogue Legacy 2 Steam CD Key - MERCADOKEYS\" \/>\n<meta property=\"og:description\" content=\"El juego Rogue Legacy 2 es un p\u00edcaro LITE geneal\u00f3gico. Eso significa que tiene todas las trampas de un p\u00edcaro t\u00edpico dentro del mismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mercadokeys.com\/product\/rogue-legacy-2-pc-steam-key-global\/\" \/>\n<meta property=\"og:site_name\" content=\"MERCADOKEYS\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-29T13:09:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mercadokeys.com\/wp-content\/uploads\/2021\/01\/Rogue-Legacy-2-PC-Steam-CD-Key.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.mercadokeys.com\/product\/rogue-legacy-2-pc-steam-key-global\/\",\"url\":\"https:\/\/www.mercadokeys.com\/product\/rogue-legacy-2-pc-steam-key-global\/\",\"name\":\"Rogue Legacy 2 Steam CD Key - MERCADOKEYS\",\"isPartOf\":{\"@id\":\"https:\/\/www.mercadokeys.com\/eng\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.mercadokeys.com\/product\/rogue-legacy-2-pc-steam-key-global\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.mercadokeys.com\/product\/rogue-legacy-2-pc-steam-key-global\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.mercadokeys.com.mx\/wp-content\/uploads\/2021\/01\/Rogue-Legacy-2-PC-Steam-CD-Key.jpg\",\"datePublished\":\"2021-01-14T00:49:26+00:00\",\"dateModified\":\"2022-06-29T13:09:50+00:00\",\"description\":\"El juego Rogue Legacy 2 es un p\u00edcaro LITE geneal\u00f3gico. Eso significa que tiene todas las trampas de un p\u00edcaro t\u00edpico dentro del mismo\",\"breadcrumb\":{\"@id\":\"https:\/\/www.mercadokeys.com\/product\/rogue-legacy-2-pc-steam-key-global\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.mercadokeys.com\/product\/rogue-legacy-2-pc-steam-key-global\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.mercadokeys.com\/product\/rogue-legacy-2-pc-steam-key-global\/#primaryimage\",\"url\":\"https:\/\/www.mercadokeys.com.mx\/wp-content\/uploads\/2021\/01\/Rogue-Legacy-2-PC-Steam-CD-Key.jpg\",\"contentUrl\":\"https:\/\/www.mercadokeys.com.mx\/wp-content\/uploads\/2021\/01\/Rogue-Legacy-2-PC-Steam-CD-Key.jpg\",\"width\":500,\"height\":500,\"caption\":\"El juego Rogue Legacy 2 es un p\u00edcaro LITE geneal\u00f3gico. Eso significa que tiene todas las trampas de un p\u00edcaro t\u00edpico\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.mercadokeys.com\/product\/rogue-legacy-2-pc-steam-key-global\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.mercadokeys.com.mx\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\/\/www.mercadokeys.com\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rogue Legacy 2 Steam CD Key\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.mercadokeys.com\/eng\/#website\",\"url\":\"https:\/\/www.mercadokeys.com\/eng\/\",\"name\":\"MERCADOKEYS\",\"description\":\"Tu Tienda de videojuegos digitales en Mexico!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.mercadokeys.com\/eng\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rogue Legacy 2 Steam CD Key - MERCADOKEYS","description":"El juego Rogue Legacy 2 es un p\u00edcaro LITE geneal\u00f3gico. Eso significa que tiene todas las trampas de un p\u00edcaro t\u00edpico dentro del mismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mercadokeys.com\/product\/rogue-legacy-2-pc-steam-key-global\/","og_locale":"en_GB","og_type":"article","og_title":"Rogue Legacy 2 Steam CD Key - MERCADOKEYS","og_description":"El juego Rogue Legacy 2 es un p\u00edcaro LITE geneal\u00f3gico. Eso significa que tiene todas las trampas de un p\u00edcaro t\u00edpico dentro del mismo","og_url":"https:\/\/www.mercadokeys.com\/product\/rogue-legacy-2-pc-steam-key-global\/","og_site_name":"MERCADOKEYS","article_modified_time":"2022-06-29T13:09:50+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/www.mercadokeys.com\/wp-content\/uploads\/2021\/01\/Rogue-Legacy-2-PC-Steam-CD-Key.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mercadokeys.com\/product\/rogue-legacy-2-pc-steam-key-global\/","url":"https:\/\/www.mercadokeys.com\/product\/rogue-legacy-2-pc-steam-key-global\/","name":"Rogue Legacy 2 Steam CD Key - MERCADOKEYS","isPartOf":{"@id":"https:\/\/www.mercadokeys.com\/eng\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mercadokeys.com\/product\/rogue-legacy-2-pc-steam-key-global\/#primaryimage"},"image":{"@id":"https:\/\/www.mercadokeys.com\/product\/rogue-legacy-2-pc-steam-key-global\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mercadokeys.com.mx\/wp-content\/uploads\/2021\/01\/Rogue-Legacy-2-PC-Steam-CD-Key.jpg","datePublished":"2021-01-14T00:49:26+00:00","dateModified":"2022-06-29T13:09:50+00:00","description":"El juego Rogue Legacy 2 es un p\u00edcaro LITE geneal\u00f3gico. Eso significa que tiene todas las trampas de un p\u00edcaro t\u00edpico dentro del mismo","breadcrumb":{"@id":"https:\/\/www.mercadokeys.com\/product\/rogue-legacy-2-pc-steam-key-global\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mercadokeys.com\/product\/rogue-legacy-2-pc-steam-key-global\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.mercadokeys.com\/product\/rogue-legacy-2-pc-steam-key-global\/#primaryimage","url":"https:\/\/www.mercadokeys.com.mx\/wp-content\/uploads\/2021\/01\/Rogue-Legacy-2-PC-Steam-CD-Key.jpg","contentUrl":"https:\/\/www.mercadokeys.com.mx\/wp-content\/uploads\/2021\/01\/Rogue-Legacy-2-PC-Steam-CD-Key.jpg","width":500,"height":500,"caption":"El juego Rogue Legacy 2 es un p\u00edcaro LITE geneal\u00f3gico. Eso significa que tiene todas las trampas de un p\u00edcaro t\u00edpico"},{"@type":"BreadcrumbList","@id":"https:\/\/www.mercadokeys.com\/product\/rogue-legacy-2-pc-steam-key-global\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.mercadokeys.com.mx\/"},{"@type":"ListItem","position":2,"name":"Tienda","item":"https:\/\/www.mercadokeys.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Rogue Legacy 2 Steam CD Key"}]},{"@type":"WebSite","@id":"https:\/\/www.mercadokeys.com\/eng\/#website","url":"https:\/\/www.mercadokeys.com\/eng\/","name":"MERCADOKEYS","description":"Tu Tienda de videojuegos digitales en Mexico!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mercadokeys.com\/eng\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"df_price":482.322916,"df_sale_price":482.322916,"df_regular_price":482.322916,"df_image_link":"https:\/\/www.mercadokeys.com.mx\/wp-content\/uploads\/2021\/01\/Rogue-Legacy-2-PC-Steam-CD-Key-300x300.jpg","_links":{"self":[{"href":"https:\/\/www.mercadokeys.com.mx\/eng\/wp-json\/wp\/v2\/product\/110357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mercadokeys.com.mx\/eng\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.mercadokeys.com.mx\/eng\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mercadokeys.com.mx\/eng\/wp-json\/wp\/v2\/media\/111067"}],"wp:attachment":[{"href":"https:\/\/www.mercadokeys.com.mx\/eng\/wp-json\/wp\/v2\/media?parent=110357"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.mercadokeys.com.mx\/eng\/wp-json\/wp\/v2\/product_brand?post=110357"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.mercadokeys.com.mx\/eng\/wp-json\/wp\/v2\/product_cat?post=110357"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.mercadokeys.com.mx\/eng\/wp-json\/wp\/v2\/product_tag?post=110357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}